{"id":2667,"date":"2020-06-01T10:52:56","date_gmt":"2020-06-01T08:52:56","guid":{"rendered":"http:\/\/tcwangen.ch\/wordpress\/?p=2667"},"modified":"2020-06-01T10:53:12","modified_gmt":"2020-06-01T08:53:12","slug":"lockerungen-per-6-juni-2020","status":"publish","type":"post","link":"https:\/\/tcwangen.ch\/wordpress\/lockerungen-per-6-juni-2020\/","title":{"rendered":"Lockerungen per 6. Juni 2020"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wie Ihr aus den Medien bestimmt alle bereits mitbekommen habt, hat der Bundesrat am 27. Mai 2020 entschieden, im Sport weitere Lockerungen zuzulassen. F\u00fcr den Tennissport, der ab dem 11. Mai unter Auflagen wieder aufgenommen werden konnte, bedeuten die Lockerungen per 6. Juni 2020 weitestgehend eine R\u00fcckkehr zur Normalit\u00e4t.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neu d\u00fcrfen ab dem 6. Juni wieder Wettk\u00e4mpfe, Turniere und Meisterschaften durchgef\u00fchrt werden. Die Garderoben und Duschen d\u00fcrfen ge\u00f6ffnet werden und die Empfehlungen, auf Doppel zu verzichten, nur die eigenen B\u00e4lle zu ber\u00fchren, nur Clubmitglieder spielen zu lassen oder f\u00fcr SeniorInnen Zeitfenster vorzusehen, werden alle aufgehoben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Trotzdem gibt es noch ein paar Regeln und Mindestschutzmassnahmen die zwingend einzuhalten sind. Auf\u00a0<\/strong><a href=\"https:\/\/tcwangen.ch\/wordpress\/corona\/\"><strong>tcwangen.ch\/wordpress\/corona<\/strong><\/a><strong> <a href=\"https:\/\/tcwangen.ch\/wordpress\/corona\/\"><\/a>findet Ihr alle n\u00f6tigen Informationen inkl. unserem aktualisierten Schutzkonzept das von jedem Mitglied zu lesen und zwingend einzuhalten ist!<\/strong> <strong>Und bitte beachtet: Bis zum 6. Juni 2020 gelten nach wie vor die bisherigen Regeln und Massnahmen!  <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Sportliche Gr\u00fcsse und bleibt gesund<br>Euer Vorstand<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie Ihr aus den Medien bestimmt alle bereits mitbekommen habt, hat der Bundesrat am 27. Mai 2020 entschieden, im Sport weitere Lockerungen zuzulassen. F\u00fcr den Tennissport, der ab dem 11. Mai unter Auflagen wieder aufgenommen werden konnte, bedeuten die Lockerungen per 6. Juni 2020 weitestgehend eine R\u00fcckkehr zur Normalit\u00e4t. Neu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,12,21],"tags":[],"class_list":["post-2667","post","type-post","status-publish","format-standard","hentry","category-infos","category-news","category-startseite"],"_links":{"self":[{"href":"https:\/\/tcwangen.ch\/wordpress\/wp-json\/wp\/v2\/posts\/2667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tcwangen.ch\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tcwangen.ch\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tcwangen.ch\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tcwangen.ch\/wordpress\/wp-json\/wp\/v2\/comments?post=2667"}],"version-history":[{"count":1,"href":"https:\/\/tcwangen.ch\/wordpress\/wp-json\/wp\/v2\/posts\/2667\/revisions"}],"predecessor-version":[{"id":2668,"href":"https:\/\/tcwangen.ch\/wordpress\/wp-json\/wp\/v2\/posts\/2667\/revisions\/2668"}],"wp:attachment":[{"href":"https:\/\/tcwangen.ch\/wordpress\/wp-json\/wp\/v2\/media?parent=2667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tcwangen.ch\/wordpress\/wp-json\/wp\/v2\/categories?post=2667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tcwangen.ch\/wordpress\/wp-json\/wp\/v2\/tags?post=2667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}